{"id":678,"date":"2020-05-12T17:02:24","date_gmt":"2020-05-12T17:02:24","guid":{"rendered":"http:\/\/minimum.photocrati.com\/?page_id=678"},"modified":"2020-05-12T17:02:24","modified_gmt":"2020-05-12T17:02:24","slug":"film-gallery","status":"publish","type":"page","link":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/","title":{"rendered":"Film Gallery"},"content":{"rendered":"\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1329,"featured_media":0,"parent":388,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-678","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Film Gallery<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Film Gallery\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"Minimum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/getimagely\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@imagely\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/film-gallery\\\/\",\"url\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/film-gallery\\\/\",\"name\":\"Film Gallery\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/#website\"},\"datePublished\":\"2020-05-12T17:02:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/film-gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/film-gallery\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/film-gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/galleries\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Film Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/#website\",\"url\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/\",\"name\":\"Minimum\",\"description\":\"A Photocrati Theme Design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demos.photocrati.com\\\/minimum\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Film Gallery","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/","og_locale":"en_US","og_type":"article","og_title":"Film Gallery","og_url":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/","og_site_name":"Minimum","article_publisher":"https:\/\/facebook.com\/getimagely","twitter_card":"summary_large_image","twitter_site":"@imagely","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/","url":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/","name":"Film Gallery","isPartOf":{"@id":"https:\/\/demos.photocrati.com\/minimum\/#website"},"datePublished":"2020-05-12T17:02:24+00:00","breadcrumb":{"@id":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/demos.photocrati.com\/minimum\/galleries\/film-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/demos.photocrati.com\/minimum\/galleries\/"},{"@type":"ListItem","position":2,"name":"Film Gallery"}]},{"@type":"WebSite","@id":"https:\/\/demos.photocrati.com\/minimum\/#website","url":"https:\/\/demos.photocrati.com\/minimum\/","name":"Minimum","description":"A Photocrati Theme Design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demos.photocrati.com\/minimum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/pages\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/users\/1329"}],"replies":[{"embeddable":true,"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":0,"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/pages\/678\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/pages\/388"}],"wp:attachment":[{"href":"https:\/\/demos.photocrati.com\/minimum\/wp-json\/wp\/v2\/media?parent=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}